{"id":39414,"date":"2024-03-12T09:30:00","date_gmt":"2024-03-12T07:30:00","guid":{"rendered":"https:\/\/www.rubi.com\/?p=39414"},"modified":"2024-03-27T16:46:21","modified_gmt":"2024-03-27T14:46:21","slug":"disque-ceramique","status":"publish","type":"post","link":"https:\/\/www.rubi.com\/fr\/blog\/disque-ceramique\/","title":{"rendered":"Quel est le meilleur disque pour couper la c\u00e9ramique ?"},"content":{"rendered":"\n<p>Il existe des disques sp\u00e9cifiques pour&nbsp;<a href=\"https:\/\/www.rubi.com\/fr\/blog\/8-meilleures-machines-pour-couper-le-marbre\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>couper la c\u00e9ramique<\/strong><\/a>. Mais comment savoir lequel est le plus appropri\u00e9 pour couper un type de mat\u00e9riau, cela d\u00e9pend en fait&nbsp;<strong>beaucoup de nos besoins de coupe<\/strong>. Nous verrons ici comment fonctionnent les disques et comment ils sont cr\u00e9\u00e9s. Cela vous permettra de choisir le disque dont nous avons besoin et \u00e0 savoir quel est le meilleur disque pour couper la c\u00e9ramique ?<\/p>\n\n\n\n<!--HubSpot Call-to-Action Code --><span class=\"hs-cta-wrapper\" id=\"hs-cta-wrapper-e0613181-7680-4cc7-82ee-d22f542ad21d\"><span class=\"hs-cta-node hs-cta-e0613181-7680-4cc7-82ee-d22f542ad21d\" id=\"hs-cta-e0613181-7680-4cc7-82ee-d22f542ad21d\"><!--[if lte IE 8]><div id=\"hs-cta-ie-element\"><\/div><![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/6786297\/e0613181-7680-4cc7-82ee-d22f542ad21d\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"hs-cta-img\" id=\"hs-cta-img-e0613181-7680-4cc7-82ee-d22f542ad21d\" style=\"border-width:0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/6786297\/e0613181-7680-4cc7-82ee-d22f542ad21d.png\"  alt=\"* Voulez-vous obtenir le Guide sur les 4 erreurs courantes \u00e0 \u00e9viter lors de  la pose de carrelage ?Cliquez ici et t\u00e9l\u00e9chargez-le gratuitement.\"\/><\/a><\/span><script charset=\"utf-8\" src=\"https:\/\/js.hscta.net\/cta\/current.js\"><\/script><script type=\"text\/javascript\"> hbspt.cta.load(6786297, 'e0613181-7680-4cc7-82ee-d22f542ad21d', {\"useNewLoader\":\"true\",\"region\":\"na1\"}); <\/script><\/span><!-- end HubSpot Call-to-Action Code -->\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1000\" height=\"542\" src=\"https:\/\/www.rubi.com\/es\/blog\/wp-content\/uploads\/2022\/06\/disco_1_baja.jpg\" alt=\"disque c\u00e9ramique\" class=\"wp-image-39419\" srcset=\"https:\/\/www.rubi.com\/fr\/blog\/wp-content\/uploads\/2022\/06\/disco_1_baja.jpg 1000w, https:\/\/www.rubi.com\/fr\/blog\/wp-content\/uploads\/2022\/06\/disco_1_baja-300x163.jpg 300w, https:\/\/www.rubi.com\/fr\/blog\/wp-content\/uploads\/2022\/06\/disco_1_baja-768x416.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">DISQUES POUR COUPER LA C\u00c9RAMIQUE : DISQUES DIAMANT\u00c9S ?<\/h2>\n\n\n\n<p>Les disques&nbsp;<strong>diamant\u00e9s sont des super-abrasif<\/strong>s&nbsp;<strong>constitu\u00e9s d\u2019un corps circulaire et<\/strong> d\u2019une couronne continue ou segment\u00e9e. Ce&nbsp;<strong>mat\u00e9riau de coupe que nous appelons bande diamant\u00e9e<\/strong>&nbsp;peut \u00eatre soud\u00e9e de diff\u00e9rentes mani\u00e8res au disque, mais la plus utilis\u00e9e par RUBI est le soudage au laser.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">LES GRAINS DE DIAMANT<\/h2>\n\n\n\n<p>Dans les disques, le<strong>&nbsp;type de fixation des grains de diamant<\/strong>&nbsp;peut \u00eatre effectu\u00e9 de 3 mani\u00e8res diff\u00e9rentes. Voici les 3 m\u00e9thodes :<strong> frittage, \u00e9lectrod\u00e9position et brasage sous vide<\/strong>. Mais dans le cas de disques <strong>couper la c\u00e9ramique, nous parlerons g\u00e9n\u00e9ralement de frittage<\/strong>.<\/p>\n\n\n\n<p>Dans le processus de frittage, les particules de diamant sont m\u00e9lang\u00e9es au liant m\u00e9tallique et consolid\u00e9es par pression \u00e0 haute temp\u00e9rature. Cette technique cr\u00e9\u00e9 diff\u00e9rentes couches de diamant qui sont expos\u00e9es \u00e0 mesure que l\u2019outil s\u2019use. Ce conglom\u00e9rat de m\u00e9tal et de diamant est appel\u00e9 une \u00ab&nbsp;jante&nbsp;\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1000\" height=\"557\" src=\"https:\/\/www.rubi.com\/es\/blog\/wp-content\/uploads\/2022\/06\/disco-2-baja.jpg\" alt=\"disque c\u00e9ramique\" class=\"wp-image-39427\" srcset=\"https:\/\/www.rubi.com\/fr\/blog\/wp-content\/uploads\/2022\/06\/disco-2-baja.jpg 1000w, https:\/\/www.rubi.com\/fr\/blog\/wp-content\/uploads\/2022\/06\/disco-2-baja-300x167.jpg 300w, https:\/\/www.rubi.com\/fr\/blog\/wp-content\/uploads\/2022\/06\/disco-2-baja-768x428.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">RELATION ENTRE LA TAILLE DES GRAINS, LEUR CONCENTRATION ET LA DURET\u00c9 DE LA JANTE<\/h2>\n\n\n\n<p>La relation entre la taille du grain de diamant, la concentration des grains et la duret\u00e9 de la jante varie en fonction des exigences de chaque disque.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Pour les mat\u00e9riaux durs<\/strong>, nous utilisons un grain fin, avec une forte concentration de diamant.<\/li>\n\n\n\n<li><strong>Pour les mat\u00e9riaux abrasifs<\/strong>, nous utilisons une taille de grain plus cons\u00e9quente, avec une faible concentration de diamant et une jante dure.<\/li>\n\n\n\n<li><strong>Si nous coupons des mat\u00e9riaux de toutes sortes<\/strong>, nous utilisons une grande taille de grain, une faible concentration de diamants et une jante fine.<\/li>\n<\/ul>\n\n\n\n<p>Id\u00e9alement,&nbsp;<strong>les deux \u00e9l\u00e9ments devraient s\u2019user en m\u00eame temps<\/strong>. Si nous avons une jante souple, le m\u00e9tal s\u2019usera et le diamant \u00e9mergera toujours pour pouvoir couper efficacement, mais la dur\u00e9e de vie du disque pour couper la c\u00e9ramique sera affect\u00e9e, en particulier lors de la coupe de mat\u00e9riaux abrasifs.<\/p>\n\n\n\n<!--HubSpot Call-to-Action Code --><span class=\"hs-cta-wrapper\" id=\"hs-cta-wrapper-26d4f7e8-ad7c-4eb4-b57d-c78edfbf8c6c\"><span class=\"hs-cta-node hs-cta-26d4f7e8-ad7c-4eb4-b57d-c78edfbf8c6c\" id=\"hs-cta-26d4f7e8-ad7c-4eb4-b57d-c78edfbf8c6c\"><!--[if lte IE 8]><div id=\"hs-cta-ie-element\"><\/div><![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/6786297\/26d4f7e8-ad7c-4eb4-b57d-c78edfbf8c6c\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"hs-cta-img\" id=\"hs-cta-img-26d4f7e8-ad7c-4eb4-b57d-c78edfbf8c6c\" style=\"border-width:0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/6786297\/26d4f7e8-ad7c-4eb4-b57d-c78edfbf8c6c.png\"  alt=\"New call-to-action\"\/><\/a><\/span><script charset=\"utf-8\" src=\"https:\/\/js.hscta.net\/cta\/current.js\"><\/script><script type=\"text\/javascript\"> hbspt.cta.load(6786297, '26d4f7e8-ad7c-4eb4-b57d-c78edfbf8c6c', {\"useNewLoader\":\"true\",\"region\":\"na1\"}); <\/script><\/span><!-- end HubSpot Call-to-Action Code -->\n\n\n\n<p><\/p>\n\n\n\n<p>Au contraire,&nbsp;<strong>si nous avons une jante trop dure, le diamant s\u2019usera sans se r\u00e9approvisionner<\/strong>&nbsp;car le liant ne s\u2019use pas en m\u00eame temps et l\u2019outil<strong>&nbsp;perdra son efficacit\u00e9 de coupe<\/strong>. C\u2019est \u00e0 ce moment-l\u00e0 que nous disons que le disque est us\u00e9.<\/p>\n\n\n\n<p>Pour r\u00e9soudre ce probl\u00e8me, nous pouvons<strong>&nbsp;utiliser un bloc de nettoyage, qui est un super-abrasif qui fera \u00e9merger des particules de diamant des couches inf\u00e9rieures<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">TYPES DE DISQUES DIAMANT\u00c9S FRITT\u00c9S<\/h2>\n\n\n\n<p>Les types de disques pour c\u00e9ramique fritt\u00e9s sont les suivants :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Bande continue<\/strong>: Garantit la meilleure finition. Ce type de disque est utilis\u00e9 pour couper des c\u00e9ramiques ou d\u2019autres mat\u00e9riaux de rev\u00eatement de pierre, avec des \u00e9paisseurs &lt;25 mm.<\/li>\n\n\n\n<li><strong>Turbo<\/strong>&nbsp;: Une excellente combinaison. Haute performance et vitesse de coupe avec des finitions de haute qualit\u00e9.<\/li>\n\n\n\n<li><strong>Viper<\/strong>: C\u2019est l\u2019\u00e9volution du disque TURBO avec une qualit\u00e9 et une vitesse sup\u00e9rieures. Il est conseill\u00e9 pour les mat\u00e9riaux \u00e0 haute duret\u00e9.<\/li>\n\n\n\n<li><strong>Segment\u00e9<\/strong>: Le plus rapide. Vitesse maximale et meilleur refroidissement du disque. Pour la d\u00e9coupe de mat\u00e9riaux d\u2019\u00e9paisseurs &gt;25 mm.<\/li>\n\n\n\n<li><strong>Turbo segment\u00e9:<\/strong>&nbsp;Pour la d\u00e9coupe de tous les types de mat\u00e9riaux avec une vitesse maximale.<\/li>\n\n\n\n<li><strong>J-Slot<\/strong>&nbsp;: Technologie de pointe. Haute vitesse dans les mat\u00e9riaux les plus durs. Sp\u00e9cialement con\u00e7u pour la coupe droite du gr\u00e8s c\u00e9rame. \u00c9limine les contraintes g\u00e9n\u00e9r\u00e9es lors de la coupe.<\/li>\n<\/ul>\n\n\n\n<p><strong>Plus la vitesse de coupe est \u00e9lev\u00e9e, plus la qualit\u00e9 de finition est faible et vice versa<\/strong>. Les disques avec un rapport vitesse-qualit\u00e9 plus \u00e9quilibr\u00e9 sont turbo et viper.<\/p>\n\n\n\n<p><strong>Dans cette vid\u00e9o, vous pouvez voir le disque diamant\u00e9 CEV-SUPERPRO 250mm fonctionnant<\/strong>&nbsp;sur un RUBI DC250-850.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Rubi DC250-850 Tile Saw From Contractors Direct\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/HKWoNDJV2zE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">COMMENT CHOISIR LE BON DISQUE DIAMANT\u00c9 ?<\/h2>\n\n\n\n<p>Maintenant que nous savons comment fonctionnent les disques, comment ils sont cr\u00e9\u00e9s, les typologies et leurs caract\u00e9ristiques, nous devons&nbsp;<strong>prendre en compte 3 aspects lors du choix d\u2019un disque c\u00e9ramique diamant\u00e9<\/strong>:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1. QUEL GENRE DE COUPE NOUS ALLONS FAIRE ?<\/h3>\n\n\n\n<p>Selon le type de coupe que nous allons faire, nous devons r\u00e9fl\u00e9chir au type de machine que nous allons utiliser. Une machine \u00e9lectrique ? une meuleuse ? Et par cons\u00e9quent, quel type de refroidissement allons-nous avoir.<\/p>\n\n\n\n<p>Nous devons garder \u00e0 l\u2019esprit que&nbsp;<strong>les disques coupent par frottement&nbsp;<\/strong>et qu\u2019ils sont super-abrasifs. Ce frottement g\u00e9n\u00e8re des temp\u00e9ratures \u00e9lev\u00e9es lors de la coupe et donne&nbsp;<strong>lieu \u00e0 2 types de coupe : la coupe \u00e0 eau et la coupe \u00e0 sec<\/strong>.<\/p>\n\n\n\n<p>Dans la coupe \u00e0 sec, le seul refroidissement est celui qui se fait au moyen de la ventilation g\u00e9n\u00e9r\u00e9e par le disque lui-m\u00eame lors de son utilisation. Les disques de coupe \u00e0 sec peuvent \u00eatre refroidis \u00e0 l\u2019eau pour une durabilit\u00e9 et une meilleure finition, mais<strong>&nbsp;les disques de coupe \u00e0 eau ne doivent jamais \u00eatre utilis\u00e9s sans eau<\/strong>.<\/p>\n\n\n\n<p>Chez RUBI, nous avons des disques pour couper la c\u00e9ramique \u00e0 la fois en coupe \u00e0 sec et \u00e0 eau. C\u2019est pourquoi avant de d\u00e9cider, nous devons savoir quelle machine nous allons utiliser et quel type de refroidissement.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2. TYPES DE MAT\u00c9RIAUX QUE NOUS DEVONS COUPER<\/h3>\n\n\n\n<p>La 2\u00e8me chose que nous devons prendre en compte est le type de mat\u00e9riaux que nous allons couper.<\/p>\n\n\n\n<p>Lorsque nous parlons de couper des c\u00e9ramiques ou des mat\u00e9riaux c\u00e9ramiques, les deux appartiennent au groupe des&nbsp;<strong>mat\u00e9riaux siliceux<\/strong>. Ces mat\u00e9riaux, qui sont principalement compos\u00e9s de silice, ont une duret\u00e9 moyenne-\u00e9lev\u00e9e, bien que certains puissent \u00e9galement avoir des taux d\u2019abrasivit\u00e9 tr\u00e8s \u00e9lev\u00e9s.<\/p>\n\n\n\n<p>Parmi les mat\u00e9riaux siliceux les plus courants se trouve le groupe qui nous int\u00e9resse : la c\u00e9ramique ou les mat\u00e9riaux c\u00e9ramiques tels que le gr\u00e8s \u00e9maill\u00e9 ou le gr\u00e8s c\u00e9rame. Le verre et le granit entrent \u00e9galement dans ce groupe.<\/p>\n\n\n\n<p>Par cons\u00e9quent, en raison de la duret\u00e9 de ces mat\u00e9riaux, nous aurons besoin&nbsp;<strong>d\u2019une combinaison de petits grains, avec une forte concentration de diamant et une jante fine<\/strong>. Ces derniers s\u2019use en m\u00eame temps que le diamant pour \u00e9viter la matit\u00e9 du disque de c\u00e9ramique et avoir une bonne performance de l\u2019outil.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3. VITESSE DE COUPE VS QUALIT\u00c9 DE FINITION<\/h3>\n\n\n\n<p>Le 3\u00e8me aspect \u00e0 prendre en compte est de savoir si nous avons besoin de vitesse de coupe ou de qualit\u00e9 des finitions.<\/p>\n\n\n\n<p>Cela d\u00e9pendra des types de coupes que nous allons faire. Ce n\u2019est pas la m\u00eame chose de faire une coupe droite ou diagonale, o\u00f9 nous pouvons avoir besoin de vitesse, que de faire un biseau dans laquelle nous aurons besoin de pr\u00e9cision et de qualit\u00e9 de finition.<\/p>\n\n\n\n<p>Tous les disques de coupe de c\u00e9ramique ne fonctionnent pas pour tous les types de d\u00e9coupe. Pour biseauter, nous recommandons les disques avec une duret\u00e9 et une \u00e9paisseur suffisantes pour r\u00e9sister \u00e0 la coupe \u00e0 45\u00ba sans se casser. L\u2019\u00e9paisseur minimale du disque pour biseau varie en fonction du diam\u00e8tre du disque.<\/p>\n\n\n\n<p>En bref, il faut d&#8217;abord savoir si on va utiliser une machine  avec coupe \u00e0 eau ou \u00e0 sec, identifier les propri\u00e9t\u00e9s de duret\u00e9 du mat\u00e9riau, et  savoir, on veut privil\u00e9gier la vitesse de coupe ou la qualit\u00e9 de finition. En r\u00e9pondant \u00e0 ces questions, nous serons en mesure de choisir le meilleur disque pour couper la c\u00e9ramique.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/www.rubi.com\/es\/blog\/wp-content\/uploads\/2022\/06\/disco-3-baja3.jpg\" alt=\"disque c\u00e9ramique rubi\" class=\"wp-image-39432\" style=\"width:750px;height:413px\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">GAMMES DE DISQUES DIAMANT\u00c9S RUBI POUR C\u00c9RAMIQUE<\/h2>\n\n\n\n<p>Parmi la gamme de disques diamant\u00e9s RUBI, nous pouvons souligner les points suivants&nbsp;:<\/p>\n\n\n\n<p><strong>Pour la coupe \u00e0 sec :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>CPR<\/strong>: Disque continu, recommand\u00e9 pour la coupe fine de gr\u00e8s c\u00e9rame d\u2019une \u00e9paisseur inf\u00e9rieure \u00e0 20 mm. Il offre l\u2019une des meilleures finitions. Disponible en diam\u00e8tres de 115 et 125 mm.<\/li>\n\n\n\n<li><strong>TCR<\/strong>: Disque de type turbo, recommand\u00e9 pour la coupe fine du gr\u00e8s c\u00e9rame qui a une haute performance et une vitesse de coupe avec des finitions de haute qualit\u00e9. Disponible en diam\u00e8tres de 115 \u2013 125 \u2013 180 \u2013 230 mm.<\/li>\n\n\n\n<li><strong>CPJ<\/strong>: Disque de type J-Slot, augmente la vitesse de coupe dans les carreaux de gr\u00e8s c\u00e9rame tr\u00e8s durs, tout en r\u00e9duisant les contraintes g\u00e9n\u00e9r\u00e9es lors de la coupe. Disponible en diam\u00e8tres de 115 et 125 mm.<\/li>\n<\/ul>\n\n\n\n<p><strong>Pour la coupe \u00e0 eau :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>CPC<\/strong>: Disque continu, recommand\u00e9 pour la coupe fine de gr\u00e8s c\u00e9rame avec des \u00e9paisseurs inf\u00e9rieures \u00e0 20 mm. Particuli\u00e8rement recommand\u00e9 pour la coupe de biseau. Disponible en diam\u00e8tres de 180 \u2013 200 \u2013 230 \u2013 250 \u2013 300 \u2013 350 mm.<\/li>\n\n\n\n<li><strong>CPX<\/strong>: Disque de type J-Slot, avec une technologie de pointe pour une grande vitesse dans la coupe droite du gr\u00e8s c\u00e9rame. Disponible en diam\u00e8tres de 200 \u2013 250 \u2013 300 mm.<\/li>\n\n\n\n<li><strong>TPI<\/strong>: Disque de type turbo, recommand\u00e9 pour la d\u00e9coupe en biseau du gr\u00e8s c\u00e9rame. Il offre une grande stabilit\u00e9 et une grande vitesse de coupe. Disponible en diam\u00e8tres de 200 \u2013 230 \u2013 250 mm.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">CLASSIFICATION DES COULEURS DES DISQUES C\u00c9RAMIQUES RUBI<\/h2>\n\n\n\n<p>Chez RUBI, nous proposons une large gamme de disques pour couper la c\u00e9ramique. Par cons\u00e9quent, nous avons opt\u00e9 pour une classification par couleurs pour faciliter le choix. Chaque couleur indique l\u2019utilisation ou l\u2019application pour laquelle ce disque est con\u00e7u \u00e0 l\u2019origine.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Rouge<\/strong>: convient si nous voulons principalement couper de&nbsp;<strong>le gr\u00e8s c\u00e9rame<\/strong><\/li>\n\n\n\n<li><strong>Violet et vert fonc\u00e9:<\/strong>&nbsp;ils sont destin\u00e9s au b\u00e9ton arm\u00e9, brique, ciment, dalle.<\/li>\n\n\n\n<li><strong>Vert<\/strong>: pour le carrelage, gr\u00e8s \u00e9maill\u00e9, gr\u00e8s c\u00e9rame<\/li>\n\n\n\n<li><strong>Bleu<\/strong>&nbsp;: pour&nbsp;<strong>les mat\u00e9riaux durs<\/strong> comme l&#8217;ardoise, gr\u00e8s, granit, gr\u00e8s rustique<\/li>\n\n\n\n<li><strong>Orange<\/strong>&nbsp;: pour&nbsp;<strong>les mat\u00e9riaux abrasifs<\/strong> comme le marbre, le granit , la brique<\/li>\n\n\n\n<li><strong>Gris<\/strong>: pour&nbsp;<strong>le marbre<\/strong> et pierre calcaire<\/li>\n\n\n\n<li><strong>Jaune<\/strong>&nbsp;:&nbsp;m\u00e9tal, plastique et bois. <\/li>\n<\/ul>\n\n\n\n<p>Nous esp\u00e9rons que gr\u00e2ce \u00e0 ses explications, il vous sera plus facile de choisir le meilleur disque pour couper la c\u00e9ramique.<\/p>\n\n\n\n<!--HubSpot Call-to-Action Code --><span class=\"hs-cta-wrapper\" id=\"hs-cta-wrapper-264c22a1-941f-4544-825a-680e870f2e29\"><span class=\"hs-cta-node hs-cta-264c22a1-941f-4544-825a-680e870f2e29\" id=\"hs-cta-264c22a1-941f-4544-825a-680e870f2e29\"><!--[if lte IE 8]><div id=\"hs-cta-ie-element\"><\/div><![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/6786297\/264c22a1-941f-4544-825a-680e870f2e29\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"hs-cta-img\" id=\"hs-cta-img-264c22a1-941f-4544-825a-680e870f2e29\" style=\"border-width:0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/6786297\/264c22a1-941f-4544-825a-680e870f2e29.png\"  alt=\"New call-to-action\"\/><\/a><\/span><script charset=\"utf-8\" src=\"https:\/\/js.hscta.net\/cta\/current.js\"><\/script><script type=\"text\/javascript\"> hbspt.cta.load(6786297, '264c22a1-941f-4544-825a-680e870f2e29', {\"useNewLoader\":\"true\",\"region\":\"na1\"}); <\/script><\/span><!-- end HubSpot Call-to-Action Code -->\n","protected":false},"excerpt":{"rendered":"<p>disque c\u00e9ramique<\/p>\n","protected":false},"author":65,"featured_media":39419,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[779],"tags":[],"coauthors":[],"class_list":["post-39414","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rubi-tools"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quel est le meilleur disque pour couper la c\u00e9ramique ? &#8211;<\/title>\n<meta name=\"description\" content=\"Optimisez vos d\u00e9coupe avec les meilleurs disques de c\u00e9ramiques. Trouvez le disque id\u00e9al pour vos projets utilisant la c\u00e9ramique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quel est le meilleur disque pour couper la c\u00e9ramique ? &#8211;\" \/>\n<meta property=\"og:description\" content=\"Optimisez vos d\u00e9coupe avec les meilleurs disques de c\u00e9ramiques. Trouvez le disque id\u00e9al pour vos projets utilisant la c\u00e9ramique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rubi.com\/fr\/blog\/disque-ceramique\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog RUBI France\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.instagram.com\/rubitools\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/RubiTools.France\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-12T07:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-27T14:46:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rubi.com\/fr\/blog\/wp-content\/uploads\/2022\/06\/disco_1_baja.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"542\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nicolas Lux\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RubiTools_Es\" \/>\n<meta name=\"twitter:site\" content=\"@RubiTools_Es\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicolas Lux\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quel est le meilleur disque pour couper la c\u00e9ramique ? &#8211;","description":"Optimisez vos d\u00e9coupe avec les meilleurs disques de c\u00e9ramiques. Trouvez le disque id\u00e9al pour vos projets utilisant la c\u00e9ramique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Quel est le meilleur disque pour couper la c\u00e9ramique ? &#8211;","og_description":"Optimisez vos d\u00e9coupe avec les meilleurs disques de c\u00e9ramiques. Trouvez le disque id\u00e9al pour vos projets utilisant la c\u00e9ramique.","og_url":"https:\/\/www.rubi.com\/fr\/blog\/disque-ceramique\/","og_site_name":"Blog RUBI France","article_publisher":"https:\/\/www.instagram.com\/rubitools\/","article_author":"https:\/\/www.facebook.com\/RubiTools.France\/","article_published_time":"2024-03-12T07:30:00+00:00","article_modified_time":"2024-03-27T14:46:21+00:00","og_image":[{"width":1000,"height":542,"url":"https:\/\/www.rubi.com\/fr\/blog\/wp-content\/uploads\/2022\/06\/disco_1_baja.jpg","type":"image\/jpeg"}],"author":"Nicolas Lux","twitter_card":"summary_large_image","twitter_creator":"@RubiTools_Es","twitter_site":"@RubiTools_Es","twitter_misc":{"Written by":"Nicolas Lux","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rubi.com\/fr\/blog\/disque-ceramique\/","url":"https:\/\/www.rubi.com\/fr\/blog\/disque-ceramique\/","name":"Quel est le meilleur disque pour couper la c\u00e9ramique ? &#8211;","isPartOf":{"@id":"https:\/\/www.rubi.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rubi.com\/fr\/blog\/disque-ceramique\/#primaryimage"},"image":{"@id":"https:\/\/www.rubi.com\/fr\/blog\/disque-ceramique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rubi.com\/fr\/blog\/wp-content\/uploads\/2022\/06\/disco_1_baja.jpg","datePublished":"2024-03-12T07:30:00+00:00","dateModified":"2024-03-27T14:46:21+00:00","description":"Optimisez vos d\u00e9coupe avec les meilleurs disques de c\u00e9ramiques. Trouvez le disque id\u00e9al pour vos projets utilisant la c\u00e9ramique.","breadcrumb":{"@id":"https:\/\/www.rubi.com\/fr\/blog\/disque-ceramique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rubi.com\/fr\/blog\/disque-ceramique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.rubi.com\/fr\/blog\/disque-ceramique\/#primaryimage","url":"https:\/\/www.rubi.com\/fr\/blog\/wp-content\/uploads\/2022\/06\/disco_1_baja.jpg","contentUrl":"https:\/\/www.rubi.com\/fr\/blog\/wp-content\/uploads\/2022\/06\/disco_1_baja.jpg","width":1000,"height":542,"caption":"disque c\u00e9ramique"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rubi.com\/fr\/blog\/disque-ceramique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rubi.com\/fr"},{"@type":"ListItem","position":2,"name":"Quel est le meilleur disque pour couper la c\u00e9ramique ?"}]},{"@type":"WebSite","@id":"https:\/\/www.rubi.com\/fr\/#website","url":"https:\/\/www.rubi.com\/fr\/","name":"Blog RUBI France","description":"","publisher":{"@id":"https:\/\/www.rubi.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rubi.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.rubi.com\/fr\/#organization","name":"RUBI Tools Espa\u00f1a Fran\u00e7ais","url":"https:\/\/www.rubi.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.rubi.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.rubi.com\/fr\/blog\/wp-content\/uploads\/2021\/09\/rubi-logo-new.png","contentUrl":"https:\/\/www.rubi.com\/fr\/blog\/wp-content\/uploads\/2021\/09\/rubi-logo-new.png","width":300,"height":300,"caption":"RUBI Tools Espa\u00f1a Fran\u00e7ais"},"image":{"@id":"https:\/\/www.rubi.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/rubitools\/","https:\/\/x.com\/RubiTools_Es","https:\/\/www.linkedin.com\/company\/rubi-group\/","https:\/\/www.youtube.com\/c\/ClubRubi"]}]}},"_links":{"self":[{"href":"https:\/\/www.rubi.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/39414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rubi.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rubi.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rubi.com\/fr\/blog\/wp-json\/wp\/v2\/users\/65"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rubi.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=39414"}],"version-history":[{"count":18,"href":"https:\/\/www.rubi.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/39414\/revisions"}],"predecessor-version":[{"id":70809,"href":"https:\/\/www.rubi.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/39414\/revisions\/70809"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rubi.com\/fr\/blog\/wp-json\/wp\/v2\/media\/39419"}],"wp:attachment":[{"href":"https:\/\/www.rubi.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=39414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rubi.com\/fr\/blog\/wp-json\/wp\/v2\/categories?post=39414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rubi.com\/fr\/blog\/wp-json\/wp\/v2\/tags?post=39414"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.rubi.com\/fr\/blog\/wp-json\/wp\/v2\/coauthors?post=39414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}