{"id":62777,"date":"2024-09-01T09:48:50","date_gmt":"2024-09-01T07:48:50","guid":{"rendered":"https:\/\/www.rubi.com\/?p=62777"},"modified":"2023-11-16T11:26:05","modified_gmt":"2023-11-16T09:26:05","slug":"o-que-e-um-cinzel-e-para-que-serve","status":"publish","type":"post","link":"https:\/\/www.rubi.com\/pt\/blog\/o-que-e-um-cinzel-e-para-que-serve\/","title":{"rendered":"O que \u00e9 um cinzel e para que serve?"},"content":{"rendered":"\n<p>Os cinz\u00e9is t\u00eam sido usados de v\u00e1rias maneiras h\u00e1 milhares de anos. No entanto, apesar de existirem diferentes tipos de cinz\u00e9is<strong>, o uso b\u00e1sico do cinzel manteve-se inalterado<\/strong> e a sua utiliza\u00e7\u00e3o \u00e9 muitas vezes essencial na <strong>coloca\u00e7\u00e3o de azulejos<\/strong>, pelo que no artigo de hoje <strong>vamos ver o que \u00e9 um cinzel e para que serve<\/strong>.<\/p>\n\n\n\n<p><a href=\"https:\/\/landing.rubi.com\/cs\/c\/?cta_guid=d93599c3-862d-4f29-9431-442340097135&amp;signature=AAH58kGDSsEHNgSffz0Rr_EaXz6y2pDgjw&amp;placement_guid=dccf123e-51b7-442a-8f47-ce17cff2aeae&amp;click=f281bc2d-12f5-45f2-9d45-892c801d7eda&amp;hsutk=0ce71fd61b06e646775c187a34daa69a&amp;canon=https%3A%2F%2Fwww.rubi.com%2Fes%2Fblog%2Fpara-que-sirve-el-cincel%2F&amp;utm_referrer=https%3A%2F%2Feuc-excel.officeapps.live.com%2F&amp;portal_id=6786297&amp;redirect_url=APefjpHGF7qUBlF1yyxABVcv7Mzl_pvVd_h-VuiTwyVz30n4RloO8wKTsZJdfKaQsJyCqbEZ6PBM4liCg7wBwnD09PBZYiNeC8jhCx3r7M3ABi4ooFot4IchAp0RiIK5SQhq9KUm7uFqM9lvS-R_DyK68UJKFymfl-CHxVLoB_FqoyVWncR0BmF4GBbRijECeoARdzItvSRZuPU_uMM40upiJIjXYMf8ciOrozswEjNoJrcTBVFZdvGnEV4Uwn8ClYc_FC4j9cg9H9j5RbJE0F4Ig4_24mOhtZc0RePrptB77hrAJbAqQlx2nNfKyByRlRVa2X25FWnuzaF9aU61s78XfsSzmz52Wmr6ktVQ3pXpmeIJFZOmpEc\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.rubi.com\/es\/blog\/wp-content\/uploads\/2023\/10\/Imagem1-1-1.jpg\" alt=\"cinzel\" class=\"wp-image-62779\" style=\"width:837px;height:468px\" width=\"837\" height=\"468\" srcset=\"https:\/\/www.rubi.com\/pt\/blog\/wp-content\/uploads\/2023\/10\/Imagem1-1-1.jpg 567w, https:\/\/www.rubi.com\/pt\/blog\/wp-content\/uploads\/2023\/10\/Imagem1-1-1-300x168.jpg 300w\" sizes=\"(max-width: 837px) 100vw, 837px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>O QUE \u00c9 UM CINZEL E PARA QUE SERVE?<\/strong><\/h2>\n\n\n\n<p>Um <strong>cinzel \u00e9 uma <\/strong>ferramenta de 20 a 30 cm de comprimento, com uma boca de a\u00e7o e reta biselada duplamente, que \u00e9 <strong>usada para esculpir pedras e metais com um martelo<\/strong>.<\/p>\n\n\n\n<p>Esta ferramenta manual apresenta uma borda de corte distinta que <strong>\u00e9 projetada especificamente para esculpir e cortar materiais duros, <\/strong>como madeira, pedra e metal. Os cinz\u00e9is <strong>s\u00e3o ferramentas essenciais<\/strong> em muitas oficinas e conjuntos de ferramentas, pois est\u00e3o entre os mais utilizados tanto na carpintaria como na alvenaria por profissionais e entusiastas da bricolage.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>QUAL A IMPORT\u00c2NCIA DO CINZEL?<\/strong><\/h2>\n\n\n\n<p>Os cinz\u00e9is podem ser feitos de diferentes materiais, como cromo-van\u00e1dio, a\u00e7o ou a\u00e7o forjado. <strong>Os menores s\u00e3o adequados para trabalhos de precis\u00e3o em madeira,<\/strong> enquanto <strong>os maiores s\u00e3o ideais para remover grandes se\u00e7\u00f5es de madeira ou remover imperfei\u00e7\u00f5es<\/strong> em alvenaria.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>TIPOS DE CINZ\u00c9IS<\/strong><\/h2>\n\n\n\n<p><strong>Existem v\u00e1rios tipos diferentes de cinz\u00e9is, cada um dos quais \u00e9 mais adequado para diferentes aplica\u00e7\u00f5es. Agora que j\u00e1 sabemos o que \u00e9 um cinzel e para que serve, vejamos alguns dos mais comuns<\/strong>:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>CINZ\u00c9IS PARA CARPINTARIA<\/strong><\/h3>\n\n\n\n<p>Usado para <strong>trabalhar com a madeira<\/strong>, \u00e9 importante escolher o tipo certo de acordo com o trabalho a ser feito. Os menores s\u00e3o melhores para os detalhes, enquanto os maiores s\u00e3o melhores para remover grandes quantidades de madeira.&nbsp;<strong>\u00c9 normal usar v\u00e1rios tipos no mesmo trabalho<\/strong>. \u00c9 melhor se o <strong>cabo tiver uma tampa de metal<\/strong> para suportar melhor os golpes cont\u00ednuos dos martelos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>CINZ\u00c9IS DE TIJOLO (OU CINZ\u00c9IS DE REFOR\u00c7O)<\/strong><\/h3>\n\n\n\n<p>Projetado especificamente <strong>para rachar<\/strong> em vez de cortar materiais duros. Eles t\u00eam uma l\u00e2mina larga para quebrar grandes superf\u00edcies, como blocos de <strong>concreto ou tijolos<\/strong>. S\u00e3o relativamente f\u00e1ceis de usar, a chave \u00e9 <strong>manter a l\u00e2mina plana<\/strong> no momento do impacto. Embora nem sempre o usem, geralmente carregam um protetor para n\u00e3o bater na m\u00e3o para que possamos segur\u00e1-los com seguran\u00e7a durante o uso.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>CINZ\u00c9IS DE MA\u00c7ONARIA:<\/strong><\/h3>\n\n\n\n<p>Ideais para <strong>cortar ladrilhos e blocos de cimento, <\/strong>tamb\u00e9m s\u00e3o usados para remover o <strong>excesso de argamassa, <\/strong>como <a href=\"https:\/\/www.rubi.com\/pt\/produto\/cinzeis-de-boca-larga\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>os cinz\u00e9is de boca larga da<\/strong><\/a><strong>&nbsp;<\/strong> RUBI. T\u00eam uma cabe\u00e7a sem brilho para quebrar os materiais. Eles tamb\u00e9m <strong>geralmente t\u00eam uma al\u00e7a<\/strong> para proteger o usu\u00e1rio e s\u00e3o relativamente pesados. Existem vers\u00f5es para fixa\u00e7\u00e3o a martelos perfuradores ou britadeiras que s\u00e3o usadas para demoli\u00e7\u00f5es.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>CINZ\u00c9IS DE BET\u00c3O<\/strong><\/h3>\n\n\n\n<p>Eles s\u00e3o usados para fazer <strong>cortes de precis\u00e3o no bet\u00e3o<\/strong>. Eles t\u00eam uma al\u00e7a e uma l\u00e2mina de borda chanfrada forte para cortar concreto com a for\u00e7a de um martelo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>ESCOPROS<\/strong><\/h2>\n\n\n\n<p>Feito de a\u00e7o temperado especificamente para <strong>o corte de metais frios<\/strong>, ou seja, aqueles que n\u00e3o s\u00e3o aquecidos por tochas ou outros dispositivos. Eles t\u00eam um \u00e2ngulo menos agudo do que um cinzel de marcenaria, <strong>a borda de corte \u00e9 forte, <\/strong>mas n\u00e3o t\u00e3o afiada. Tamb\u00e9m podem ser feitos de cobre-ber\u00edlio quando quer que eles n\u00e3o produzam fa\u00edscas quando colidem com os metais. Interior de este tipo de cinz\u00e9is <strong>distinguimos<\/strong> <strong>os seguintes subtipos<\/strong>:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>ESCOPROS PLANOS:<\/strong><\/h3>\n\n\n\n<p>Mais comumente usado para <strong>cortar barras e hastes e cortar chapas de metal<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>ESCOPROS CRUZADOS:<\/strong><\/h3>\n\n\n\n<p>Especialmente concebidos para <strong>o corte de ranhuras<\/strong>, t\u00eam uma l\u00e2mina estreita colocada atr\u00e1s da borda reta.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>ESCOPROS NARIZ REDONDO:<\/strong><\/h3>\n\n\n\n<p>S\u00e3o usados para fazer <strong>ranhuras semicirculares<\/strong> para dutos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>ESCOPROS PONTA DE DIAMANTE:<\/strong><\/h3>\n\n\n\n<p>Para <strong>remover materiais indesejados<\/strong> e detritos de cantos e outras \u00e1reas de dif\u00edcil acesso.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>COMO USAR O CINZEL?<\/strong><\/h2>\n\n\n\n<p>Agora que conhecemos os diferentes tipos de cinz\u00e9is, <strong>vamos ver como usar um cinzel<\/strong>:<\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\">\n<li>O mais importante \u00e9 <strong>escolher o tipo certo de cinzel <\/strong>para o trabalho a ser feito, tendo em conta o tamanho do cinzel e a forma da l\u00e2mina. Temos de nos certificar de que <strong>est\u00e1 em boas condi\u00e7\u00f5es<\/strong> para trabalhar e afi\u00e1-lo, se necess\u00e1rio.<\/li>\n\n\n\n<li><strong>Segure o cinzel com folga<\/strong>, colocando cuidadosamente a ponta contra a \u00e1rea que pretende remover. Coloque o cinzel de modo que toda a largura da l\u00e2mina fique encostada ao material a remover e o bisel fique paralelo \u00e0 superf\u00edcie.<\/li>\n\n\n\n<li><strong>Pegue um martelo e bata na cabe\u00e7a do cinzel<\/strong> com a for\u00e7a apropriada. Use a cabe\u00e7a do cinzel para remover as pe\u00e7as que queremos e que j\u00e1 sa\u00edram.<\/li>\n\n\n\n<li><strong>Continue a golpear<\/strong> a cabe\u00e7a do cinzel com o martelo <strong>at\u00e9 que todo o material desejado tenha sido removido<\/strong>.<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.rubi.com\/es\/blog\/wp-content\/uploads\/2023\/10\/Imagem2-1-2.jpg\" alt=\"CINZEL\" class=\"wp-image-62788\" style=\"width:844px;height:564px\" width=\"844\" height=\"564\" srcset=\"https:\/\/www.rubi.com\/pt\/blog\/wp-content\/uploads\/2023\/10\/Imagem2-1-2.jpg 567w, https:\/\/www.rubi.com\/pt\/blog\/wp-content\/uploads\/2023\/10\/Imagem2-1-2-300x201.jpg 300w\" sizes=\"(max-width: 844px) 100vw, 844px\" \/><\/figure>\n\n\n\n<p>Agora que j\u00e1 sabe mais sobre cinz\u00e9is e para que servem, os seus tipos e como us\u00e1-los, o que achou do artigo? Conhecia todos os tipos de cinz\u00e9is? Aguardamos o seu feedback.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste artigo vamos mostrar-lhe o que \u00e9 um cinzel e para que serve. Os diferentes tipos e os mais recomendados para cada trabalho.<\/p>\n","protected":false},"author":47,"featured_media":28340,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[840],"tags":[1647],"class_list":["post-62777","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rubi-tools","tag-cinzel-ceramica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O que \u00e9 um cinzel e para que serve? &#8211; RUBI Portugal<\/title>\n<meta name=\"description\" content=\"Neste artigo vamos mostrar-lhe o que \u00e9 um cinzel e para que serve. Os diferentes tipos e os mais recomendados para cada trabalho.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que \u00e9 um cinzel e para que serve? &#8211; RUBI Portugal\" \/>\n<meta property=\"og:description\" content=\"Neste artigo vamos mostrar-lhe o que \u00e9 um cinzel e para que serve. Os diferentes tipos e os mais recomendados para cada trabalho.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rubi.com\/pt\/blog\/o-que-e-um-cinzel-e-para-que-serve\/\" \/>\n<meta property=\"og:site_name\" content=\"RUBI Portugal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.instagram.com\/rubitools\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/RubiToolsPortugal\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-01T07:48:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rubi.com\/blog\/es\/blog\/wp-content\/uploads\/2021\/04\/70924_a_01.jpg\" \/>\n<meta name=\"author\" content=\"Alice\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.rubi.com\/blog\/es\/blog\/wp-content\/uploads\/2021\/04\/70924_a_01.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/www.tiktok.com\/@rubi_tools\" \/>\n<meta name=\"twitter:site\" content=\"@RubiTools_Es\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alice\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O que \u00e9 um cinzel e para que serve? &#8211; RUBI Portugal","description":"Neste artigo vamos mostrar-lhe o que \u00e9 um cinzel e para que serve. Os diferentes tipos e os mais recomendados para cada trabalho.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_PT","og_type":"article","og_title":"O que \u00e9 um cinzel e para que serve? &#8211; RUBI Portugal","og_description":"Neste artigo vamos mostrar-lhe o que \u00e9 um cinzel e para que serve. Os diferentes tipos e os mais recomendados para cada trabalho.","og_url":"https:\/\/www.rubi.com\/pt\/blog\/o-que-e-um-cinzel-e-para-que-serve\/","og_site_name":"RUBI Portugal","article_publisher":"https:\/\/www.instagram.com\/rubitools\/","article_author":"https:\/\/www.facebook.com\/RubiToolsPortugal\/","article_published_time":"2024-09-01T07:48:50+00:00","og_image":[{"url":"https:\/\/www.rubi.com\/blog\/es\/blog\/wp-content\/uploads\/2021\/04\/70924_a_01.jpg","type":"","width":"","height":""}],"author":"Alice","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.rubi.com\/blog\/es\/blog\/wp-content\/uploads\/2021\/04\/70924_a_01.jpg","twitter_creator":"@https:\/\/www.tiktok.com\/@rubi_tools","twitter_site":"@RubiTools_Es","twitter_misc":{"Written by":"Alice","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rubi.com\/pt\/blog\/o-que-e-um-cinzel-e-para-que-serve\/","url":"https:\/\/www.rubi.com\/pt\/blog\/o-que-e-um-cinzel-e-para-que-serve\/","name":"O que \u00e9 um cinzel e para que serve? &#8211; RUBI Portugal","isPartOf":{"@id":"https:\/\/www.rubi.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rubi.com\/pt\/blog\/o-que-e-um-cinzel-e-para-que-serve\/#primaryimage"},"image":{"@id":"https:\/\/www.rubi.com\/pt\/blog\/o-que-e-um-cinzel-e-para-que-serve\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rubi.com\/pt\/blog\/wp-content\/uploads\/2021\/04\/70924_a_01.jpg","datePublished":"2024-09-01T07:48:50+00:00","description":"Neste artigo vamos mostrar-lhe o que \u00e9 um cinzel e para que serve. Os diferentes tipos e os mais recomendados para cada trabalho.","breadcrumb":{"@id":"https:\/\/www.rubi.com\/pt\/blog\/o-que-e-um-cinzel-e-para-que-serve\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rubi.com\/pt\/blog\/o-que-e-um-cinzel-e-para-que-serve\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.rubi.com\/pt\/blog\/o-que-e-um-cinzel-e-para-que-serve\/#primaryimage","url":"https:\/\/www.rubi.com\/pt\/blog\/wp-content\/uploads\/2021\/04\/70924_a_01.jpg","contentUrl":"https:\/\/www.rubi.com\/pt\/blog\/wp-content\/uploads\/2021\/04\/70924_a_01.jpg","width":1029,"height":687,"caption":"Cincel herramienta"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rubi.com\/pt\/blog\/o-que-e-um-cinzel-e-para-que-serve\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rubi.com\/pt\/"},{"@type":"ListItem","position":2,"name":"O que \u00e9 um cinzel e para que serve?"}]},{"@type":"WebSite","@id":"https:\/\/www.rubi.com\/pt\/#website","url":"https:\/\/www.rubi.com\/pt\/","name":"RUBI Portugal","description":"","publisher":{"@id":"https:\/\/www.rubi.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rubi.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.rubi.com\/pt\/#organization","name":"RUBI Tools Portugu\u00eas","url":"https:\/\/www.rubi.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.rubi.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.rubi.com\/fr\/blog\/wp-content\/uploads\/2021\/09\/rubi-logo-new.png","contentUrl":"https:\/\/www.rubi.com\/fr\/blog\/wp-content\/uploads\/2021\/09\/rubi-logo-new.png","width":300,"height":300,"caption":"RUBI Tools Portugu\u00eas"},"image":{"@id":"https:\/\/www.rubi.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/rubitools\/","https:\/\/x.com\/RubiTools_Es","https:\/\/www.linkedin.com\/company\/rubi-group\/","https:\/\/www.youtube.com\/c\/ClubRubi"]}]}},"_links":{"self":[{"href":"https:\/\/www.rubi.com\/pt\/blog\/wp-json\/wp\/v2\/posts\/62777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rubi.com\/pt\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rubi.com\/pt\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rubi.com\/pt\/blog\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rubi.com\/pt\/blog\/wp-json\/wp\/v2\/comments?post=62777"}],"version-history":[{"count":-1,"href":"https:\/\/www.rubi.com\/pt\/blog\/wp-json\/wp\/v2\/posts\/62777\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rubi.com\/pt\/blog\/wp-json\/wp\/v2\/media\/28340"}],"wp:attachment":[{"href":"https:\/\/www.rubi.com\/pt\/blog\/wp-json\/wp\/v2\/media?parent=62777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rubi.com\/pt\/blog\/wp-json\/wp\/v2\/categories?post=62777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rubi.com\/pt\/blog\/wp-json\/wp\/v2\/tags?post=62777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}